{"id":20,"date":"2018-12-06T16:53:59","date_gmt":"2018-12-06T15:53:59","guid":{"rendered":"https:\/\/www.bitmat.it\/visions\/?p=20"},"modified":"2018-12-20T12:40:10","modified_gmt":"2018-12-20T11:40:10","slug":"xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento","status":"publish","type":"post","link":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/","title":{"rendered":"Xerox: sopravvive chi meglio si adatta al cambiamento"},"content":{"rendered":"<p><em>\u201cCome insegnava Darwin, non sopravvive il pi\u00f9 forte ma chi si adatta meglio al cambiamento. Tutte le aziende \u2013 clienti finali, rivenditori e fornitori di tecnologia \u2013 sono impattate in modo crescente dalla Digital Transformation, che presenta opportunit\u00e0 formidabili a chi sa interpretarle e coglierle prima degli altri\u201d <\/em>esordisce <strong>Alberto Calvieri<\/strong>, European Marketing Manager, Indirect Managed Channels Italy Entry Channel Marketing Manager, Dir. &amp; Indir. Channels di <a href=\"https:\/\/www.xerox.it\/\">Xerox Italia<\/a>.<\/p>\n<p>Ma come devono muoversi allora le imprese per essere vincenti? <em>\u201cPer sfuggire alle logiche della guerra dei prezzi in Internet, le Aziende devono adottare un approccio basato su un ecosistema di tecnologie digitali, soluzioni e competenze che le differenzi dalla concorrenza e generi valore per partner e clienti, senza puntare solo sul prezzo pi\u00f9 basso\u201d<\/em>.<\/p>\n<p>Proprio la direzione in cui si muove Xerox, che <em>\u201cha investito significativamente per sviluppare questo ecosistema &#8211; ConnectKey &#8211; ed \u00e8 quindi ben equipaggiata per aiutare i rivenditori e i loro clienti a cogliere le opportunit\u00e0 dei cambiamenti attuali e futuri\u201d.<\/em><\/p>\n<p>In questo scenario per\u00f2, il 2019, si propone come un anno s\u00ec ricco di opportunit\u00e0, ma anche di sfide che ostacolano il cambiamento, che per\u00f2 possono essere affrontate nella maniera pi\u00f9 corretta se si ha a disposizione la giusta tecnologia. \u201c<em>I principali ostacoli sono di tipo psicologico (\u201caspetto ancora un po\u2019 e forse andr\u00e0 meglio\u2026, intanto abbasso i prezzi\u201d) e di competenze, perch\u00e9 in un contesto sempre pi\u00f9 basato su processi digitali non si pu\u00f2 improvvisare. Occorre soprattutto conoscere le esigenze dei propri clienti e ci\u00f2 che il mercato offre per soddisfarle attraverso processi digitali, veloci ed efficienti. Ad esempio, un rivenditore che conoscesse la tecnologia Xerox ConnectKey e la soluzione PostHello! potrebbe fare risparmiare agli studi legali molte ore spese dai loro assistenti negli uffici postali, oppure con la soluzione \u201cEasy Translator\u201d potrebbe permettere ai ristoranti di stampare il men\u00f9 tradotto nelle lingue dei clienti stranieri con cui non riescono a comunicare e ottenere cos\u00ec, in pochi istanti, men\u00f9 identici a quello originale stampati nelle lingue dei clienti che altrimenti potrebbero cercare un altro ristorante&#8230; Naturalmente, in un contesto sempre pi\u00f9 globale, questa \u201capp\u201d pu\u00f2 beneficiare aziende di qualsiasi settore. Anche questa \u00e8 Digital Transformation e si possono fare molte cose per rimuovere gli ostacoli. Gli investimenti richiesti partono da poche centinaia di euro e sono a portata di qualsiasi PMI. Permettono inoltre di porre una solida base su cui continuare ad offrire soluzioni e servizi a valore aggiunto, fidelizzando sempre di pi\u00f9 i clienti\u201d<\/em>.<\/p>\n<p>In questo mondo cambia anche il ruolo del canale, che necessita di nuovi supporti e nuovi strumenti.<\/p>\n<p>Conclude Calvieri: <em>\u201cI Vendor possono fare molto per promuovere i vantaggi del cambiamento e aiutare i Partner di Canale a cogliere enormi opportunit\u00e0. Nella stampa ad esempio, Xerox ha lanciato molte stampanti e multifunzione intelligenti, dei veri \u201cassistenti del posto di lavoro\u201d che offrono soluzioni come la traduzione di documenti in circa 50 lingue, la conversione di testi in file audio, l\u2019invio di raccomandate e molto altro, tutto in piena sicurezza e connesso al cloud. I rivenditori possono guadagnare, oltre che dalla vendita dell\u2019hardware, dei consumabili e dell\u2019assistenza, anche dalla vendita delle soluzioni e di servizi, che fidelizzano maggiormente i clienti. Possono anche certificarsi per sviluppare soluzioni ad hoc ed eventualmente pubblicarle sulla Xerox App Gallery per venderle su scala locale o mondiale\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019<\/p>\n","protected":false},"author":1,"featured_media":92,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[5,4],"class_list":{"0":"post-20","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-previsioni-per-il-2019","8":"tag-alberto-calvieri","9":"tag-xerox"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Xerox: sopravvive chi meglio si adatta al cambiamento - Previsioni per il 2025<\/title>\n<meta name=\"description\" content=\"Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xerox: sopravvive chi meglio si adatta al cambiamento\" \/>\n<meta property=\"og:description\" content=\"Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Previsioni per il 2025\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/BitMATnews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/BitMATnews\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-06T15:53:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T11:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bitmat.it\/visions\/files\/2018\/12\/Alberto-Calvieri-hi-res-683x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione BitMAT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/BitMATnews\" \/>\n<meta name=\"twitter:site\" content=\"@BitMATnews\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione BitMAT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/\"},\"author\":{\"name\":\"Redazione BitMAT\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/#\\\/schema\\\/person\\\/4cd1e4627f78f4fbed810748dc1a20d4\"},\"headline\":\"Xerox: sopravvive chi meglio si adatta al cambiamento\",\"datePublished\":\"2018-12-06T15:53:59+00:00\",\"dateModified\":\"2018-12-20T11:40:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/\"},\"wordCount\":556,\"image\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/files\\\/2018\\\/12\\\/Alberto-Calvieri-hi-res.jpg\",\"keywords\":[\"Alberto Calvieri\",\"Xerox\"],\"articleSection\":[\"Previsioni per il 2019\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/\",\"url\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/\",\"name\":\"Xerox: sopravvive chi meglio si adatta al cambiamento - Previsioni per il 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/files\\\/2018\\\/12\\\/Alberto-Calvieri-hi-res.jpg\",\"datePublished\":\"2018-12-06T15:53:59+00:00\",\"dateModified\":\"2018-12-20T11:40:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/#\\\/schema\\\/person\\\/4cd1e4627f78f4fbed810748dc1a20d4\"},\"description\":\"Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/files\\\/2018\\\/12\\\/Alberto-Calvieri-hi-res.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/files\\\/2018\\\/12\\\/Alberto-Calvieri-hi-res.jpg\",\"width\":2048,\"height\":3072},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/previsioni-per-il-2019\\\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xerox: sopravvive chi meglio si adatta al cambiamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/#website\",\"url\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/\",\"name\":\"Previsioni per il 2025\",\"description\":\"Interviste e previsioni per il 2025, ICT, mercati, trend, tecnologie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/#\\\/schema\\\/person\\\/4cd1e4627f78f4fbed810748dc1a20d4\",\"name\":\"Redazione BitMAT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g\",\"caption\":\"Redazione BitMAT\"},\"description\":\"BitMAT Edizioni \u00e8 una casa editrice che ha sede a Milano con una copertura a 360\u00b0 per quanto riguarda la comunicazione rivolta agli specialisti dell'lnformation &amp; Communication Technology.\",\"sameAs\":[\"https:\\\/\\\/www.bitmat.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/BitMATnews\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/BitMATnews\"],\"url\":\"https:\\\/\\\/www.bitmat.it\\\/visions\\\/author\\\/bitmat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Xerox: sopravvive chi meglio si adatta al cambiamento - Previsioni per il 2025","description":"Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/","og_locale":"it_IT","og_type":"article","og_title":"Xerox: sopravvive chi meglio si adatta al cambiamento","og_description":"Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019","og_url":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/","og_site_name":"Previsioni per il 2025","article_publisher":"http:\/\/www.facebook.com\/BitMATnews","article_author":"https:\/\/www.facebook.com\/BitMATnews","article_published_time":"2018-12-06T15:53:59+00:00","article_modified_time":"2018-12-20T11:40:10+00:00","og_image":[{"width":683,"height":1024,"url":"https:\/\/www.bitmat.it\/visions\/files\/2018\/12\/Alberto-Calvieri-hi-res-683x1024.jpg","type":"image\/jpeg"}],"author":"Redazione BitMAT","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/BitMATnews","twitter_site":"@BitMATnews","twitter_misc":{"Scritto da":"Redazione BitMAT","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#article","isPartOf":{"@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/"},"author":{"name":"Redazione BitMAT","@id":"https:\/\/www.bitmat.it\/visions\/#\/schema\/person\/4cd1e4627f78f4fbed810748dc1a20d4"},"headline":"Xerox: sopravvive chi meglio si adatta al cambiamento","datePublished":"2018-12-06T15:53:59+00:00","dateModified":"2018-12-20T11:40:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/"},"wordCount":556,"image":{"@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bitmat.it\/visions\/files\/2018\/12\/Alberto-Calvieri-hi-res.jpg","keywords":["Alberto Calvieri","Xerox"],"articleSection":["Previsioni per il 2019"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.bitmat.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/","url":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/","name":"Xerox: sopravvive chi meglio si adatta al cambiamento - Previsioni per il 2025","isPartOf":{"@id":"https:\/\/www.bitmat.it\/visions\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#primaryimage"},"image":{"@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bitmat.it\/visions\/files\/2018\/12\/Alberto-Calvieri-hi-res.jpg","datePublished":"2018-12-06T15:53:59+00:00","dateModified":"2018-12-20T11:40:10+00:00","author":{"@id":"https:\/\/www.bitmat.it\/visions\/#\/schema\/person\/4cd1e4627f78f4fbed810748dc1a20d4"},"description":"Differenziarsi dalla concorrenza, puntare su nuove tecnologie e produrre valore per partner e clienti i must per il 2019","breadcrumb":{"@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#primaryimage","url":"https:\/\/www.bitmat.it\/visions\/files\/2018\/12\/Alberto-Calvieri-hi-res.jpg","contentUrl":"https:\/\/www.bitmat.it\/visions\/files\/2018\/12\/Alberto-Calvieri-hi-res.jpg","width":2048,"height":3072},{"@type":"BreadcrumbList","@id":"https:\/\/www.bitmat.it\/visions\/previsioni-per-il-2019\/xerox-sopravvive-chi-meglio-si-adatta-al-cambiamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bitmat.it\/visions\/"},{"@type":"ListItem","position":2,"name":"Xerox: sopravvive chi meglio si adatta al cambiamento"}]},{"@type":"WebSite","@id":"https:\/\/www.bitmat.it\/visions\/#website","url":"https:\/\/www.bitmat.it\/visions\/","name":"Previsioni per il 2025","description":"Interviste e previsioni per il 2025, ICT, mercati, trend, tecnologie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bitmat.it\/visions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.bitmat.it\/visions\/#\/schema\/person\/4cd1e4627f78f4fbed810748dc1a20d4","name":"Redazione BitMAT","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g","caption":"Redazione BitMAT"},"description":"BitMAT Edizioni \u00e8 una casa editrice che ha sede a Milano con una copertura a 360\u00b0 per quanto riguarda la comunicazione rivolta agli specialisti dell'lnformation &amp; Communication Technology.","sameAs":["https:\/\/www.bitmat.it\/","https:\/\/www.facebook.com\/BitMATnews","https:\/\/x.com\/https:\/\/twitter.com\/BitMATnews"],"url":"https:\/\/www.bitmat.it\/visions\/author\/bitmat\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/posts\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":3,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/posts\/20\/revisions"}],"predecessor-version":[{"id":93,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/posts\/20\/revisions\/93"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/media\/92"}],"wp:attachment":[{"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/media?parent=20"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/categories?post=20"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bitmat.it\/visions\/wp-json\/wp\/v2\/tags?post=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}