{"id":4829,"date":"2020-11-01T14:54:28","date_gmt":"2020-11-01T13:54:28","guid":{"rendered":"https:\/\/www.bitmat.it\/specialesicurezza\/?p=4829"},"modified":"2020-11-01T14:54:33","modified_gmt":"2020-11-01T13:54:33","slug":"fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020","status":"publish","type":"post","link":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020","title":{"rendered":"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020"},"content":{"rendered":"\n<p><strong>Fortinet<\/strong> fa il punto su come \u00e8 cambiato il panorama della sicurezza nell&#8217;anno in corso.<\/p>\n\n\n\n<p>Nel 2020 i team di cybersecurity hanno dovuto fare i conti con cambiamenti imprevedibili nelle strutture di rete e nelle strategie di attacco. Mentre la pandemia di <a href=\"https:\/\/www.lineaedp.it\/news\/49293\/spam-e-phishing-su-covid-19-nei-primi-sei-mesi-del-2020\/\">COVID-19<\/a> continua a mettere in difficolt\u00e0 aziende e singoli individui in tutto il mondo, il panorama delle minacce informatiche \u00e8 diventato pi\u00f9 complesso e fitto di quanto non fosse prima. Molte aziende hanno avuto difficolt\u00e0 ad adattarsi per gestire e contenere tali minacce, crescenti e in continua evoluzione, avendo gi\u00e0 dovuto far fronte a criticit\u00e0 operative in seguito al rapido trasferimento della forza lavoro in remoto.<\/p>\n\n\n\n<p><strong>Oggi le minacce informatiche sono in costante trasformazione:<\/strong> le aziende devono continuamente aggiornarsi sull\u2019<a href=\"https:\/\/www.fortinet.com\/fortiguard\/labs?utm_source=pr&amp;utm_campaign=FortiGuardLabs\">attuale scenario<\/a> e investire le risorse necessarie per proteggere quella che oggi \u00e8 &#8211; e sar\u00e0 a tempo indefinito &#8211; una superficie d&#8217;attacco pi\u00f9 ampia e vulnerabile. Il panorama delle minacce informatiche \u00e8 cambiato drammaticamente e i relativi rischi per le reti rimangono elevati. Un&#8217;intelligence delle minacce accurata e attiva \u00e8 oggi quanto mai necessaria e il report sulle minacce presentato da Fortinet qui di seguito evidenzia la capacit\u00e0 della community di cybercriminali di adattarsi e sfruttare le nuove opportunit\u00e0:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-tecnologia-at-home-come-gateway-all-impresa\"><strong>La tecnologia \u2018at-home\u2019 come gateway all&#8217;impresa<\/strong><\/h3>\n\n\n\n<p>Prima l\u2019attenzione dei team di security era focalizzata sulla protezione degli utenti dalle minacce, delle applicazioni e della rete e sull\u2019implementazione di una connessione sicura per le risorse all&#8217;interno del perimetro della rete. Ora, a causa di un esponenziale aumento dell\u2019Internet of Things (IoT) e una maggiore dipendenza dalle reti domestiche e dai dispositivi consumer, come i router e i modem (cosa di cui i cybercriminali si sono accorti rapidamente), le priorit\u00e0 sono cambiate. L&#8217;incremento del lavoro da remoto ha evidenziato la necessit\u00e0 di mettere in sicurezza i dispositivi personali utilizzati per connettersi alla rete aziendale, compresi smartphone, tablet, computer portatili e PC. Per gli hacker, questo cambiamento rappresenta un&#8217;opportunit\u00e0 unica da sfruttare e introdursi nelle reti aziendali (o, almeno, sui dispositivi utilizzati per accedere a tali reti). Questi device sono vulnerabili e i ricercatori Fortinet hanno individuato la formazione di grandi BotNet che possono essere utilizzate per lanciare attacchi DDoS o distribuire malware destinati all&#8217;impresa.<\/p>\n\n\n\n<p>Oggi, i cybercriminali dimostrano di comprendere meglio la tecnologia e di avere accesso a risorse pi\u00f9 sofisticate, rendendo pi\u00f9 impegnativo che mai per i team IT proteggere le risorse distribuite. Attraverso l&#8217;uso di AI e strumenti di machine learning, ad esempio, i cybercriminali sfruttano appieno la superficie di attacco in espansione e bypassano con successo le protezioni tradizionali. A causa di questi progressi nei metodi e nelle tecnologie di attacco, i team IT lottano per stare al passo con gli sviluppi, come il ransomware di ultima generazione e le minacce di phishing utilizzate per compromettere i dispositivi IoT at-home.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-gli-attacchi-ransomware-diventano-sempre-pi-sofisticati\"><strong>Gli attacchi ransomware diventano sempre pi\u00f9 sofisticati<\/strong><\/h3>\n\n\n\n<p>Gli attacchi ransomware costituiscono da sempre una fonte di grande preoccupazione per le imprese. Ma negli ultimi mesi sono diventati sempre pi\u00f9 frequenti e dispendiosi &#8211; sia in termini di tempi di inattivit\u00e0 che di danni. Fortinet rileva che queste minacce persistono a lungo e sono diventate ancora pi\u00f9 complesse: ci\u00f2 \u00e8 dovuto al fatto che il ransomware sia ancora pi\u00f9 facilmente accessibile agli hacker tramite i marketplace di DarkNet. Le nuove tecnologie ransomware, compreso il ransomware-as-a-service, sono poco costose e relativamente semplici da implementare.<\/p>\n\n\n\n<p>Il team Fortinet ha rilevato ransomware in email, allegati e documenti riguardanti comunicazioni relative alla pandemia di COVID-19. Queste minacce si fanno sempre pi\u00f9 sofisticate. Per citare alcuni esempi specifici di ransomware, il NetWalker, Ransomware-GVZ e CoViper: dei tre, CoViper si \u00e8 rivelato particolarmente allarmante, dal momento che riscrive il master boot record (MBR) del computer prima di criptare i dati. Il team Fortinet ha osservato in passato diversi attacchi in cui gli hacker hanno sfruttato i wiper MBR combinati con il ransomware per danneggiare i PC, ma si tratta di una strategia insolitamente aggressiva.<\/p>\n\n\n\n<p>Verso la fine del primo semestre dell&#8217;anno, ci sono state anche diverse segnalazioni di gruppi di minaccia potenzialmente sostenuti da Stati membri che hanno attaccato organizzazioni coinvolte nella ricerca relativa al COVID-19 negli Stati Uniti e in altri Paesi. Inoltre, gli hacker hanno trasferito i dati critici su server aperti e hanno minacciato di renderli pubblici a meno che non venissero assecondate le loro richieste.<\/p>\n\n\n\n<p>Con l&#8217;evolversi di queste minacce, i team di security devono condividere le informazioni in tempo reale per adeguarsi alle ultime tendenze e metodi di attacco. Questo comprende l&#8217;aggiornamento sugli strumenti utilizzati dai cybercriminali per massimizzare l&#8217;impatto degli attacchi, compresi i social media e i motori di ricerca Darknet, e modificare le strategie attuali. Alle aziende si consiglia di mantenere i dati criptati, per contrastare le pi\u00f9 recenti e innovative strategie di attacco.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-il-phishing-evolve-verso-il-machine-learning\"><strong>Il Phishing evolve verso il Machine Learning<\/strong><\/h3>\n\n\n\n<p>Inizialmente, la maggior parte degli attacchi di phishing era facilmente prevenibile, rappresentando un rischio solo per gli utenti pi\u00f9 ingenui. Queste truffe utilizzano generalmente tattiche di social engineering per sottrarre le credenziali a utenti ignari, per lo pi\u00f9 via email. In altri casi, un messaggio particolarmente convincente viene utilizzato per convincere una vittima a cliccare un link che installa malware o espone dati sensibili.<\/p>\n\n\n\n<p>Sempre pi\u00f9 spesso questi attacchi sono utilizzati per anticiparne altri sia on-premise che cloud service. Oggi le strategie di phishing sono pi\u00f9 sofisticate e si sono evolute per colpire i punti deboli che si trovano ai confini delle reti aziendali. Nella maggior parte delle aziende i dipendenti oggi sono pi\u00f9 consapevoli sui pericoli del phishing via e-mail e adottano maggiori precauzioni quando incappano in link sospetti, ma gli hacker hanno iniziato ad adattare anche il loro approccio. Ad esempio, i cybercriminali prendono di mira le reti domestiche non protette e i telelavoratori alle prime armi che non hanno una formazione adeguata in materia di cybersecurity per sottrarre informazioni personali e lanciare attacchi alle reti aziendali a cui sono collegati.<\/p>\n\n\n\n<p>In molti sfruttano il machine learning per creare, testare e distribuire rapidamente messaggi con contenuti visivi sempre pi\u00f9 realistici che inducono uno stress e un disagio emotivo nei destinatari. I cybercriminali possono effettivamente analizzare gli attacchi e perfezionare le proprie strategie per garantire la massima efficacia. Gli attacchi di phishing pi\u00f9 recenti includono truffe che millantano di supportare gli utenti mediante l&#8217;accesso a forniture sanitarie o dispositivi di protezione personale difficili da reperire o offrire supporto dall&#8217;helpdesk ai lavoratori a distanza.<\/p>\n\n\n\n<p>La maggior parte di questi attacchi di phishing contiene payload dannosi &#8211; tra cui ransomware, virus e remote access trojans (RAT) concepiti per fornire ai criminali l&#8217;accesso remoto ai sistemi endpoint, consentendo loro di eseguire exploit di Remote Desktop Protocol (RDP).<\/p>\n\n\n\n<p>Il team Fortinet ha registrato un significativo picco nel phishing via web, a partire dalla serie di minacce informatiche HTML\/Phishing tra gennaio e febbraio 2020 e che si \u00e8 protratto fino alla fine di maggio. Analoghi HTML &#8211; \/ScrInject (attacchi con l&#8217;iniezione di script del browser) e \/REDIR (schemi di reindirizzamento del browser) &#8211; hanno anch&#8217;essi contribuito all&#8217;aumento dei tentativi di phishing nel corso dell&#8217;anno. Il malware web-based tende a bypassare la maggior parte dei comuni sistemi antivirus, con maggiori possibilit\u00e0 di successo.<\/p>\n\n\n\n<p>I professionisti della sicurezza dovrebbero tenere presente che nel 2020 il browser \u00e8 stato finora un vettore chiave per il malware e questa tendenza continuer\u00e0 probabilmente a verificarsi anche il prossimo anno. Ci\u00f2 riflette il calo registrato del traffico web aziendale, generalmente ispezionato, e l&#8217;aumento del traffico web da remoto dovuto al passaggio al lavoro a distanza. Questo avvantaggia i cybercriminali che hanno adeguato i loro attacchi prendendo di mira il traffico che ora inonda reti meno sicure. Per questo motivo, le aziende devono fornire ai lavoratori da remoto le conoscenze e la formazione necessarie per proteggere le proprie reti personali e la rete aziendale connessa, ma anche fornire risorse aggiuntive, come ad esempio nuove soluzioni di rilevamento e Endpoint Detection and Response (EDR) in grado di rilevare e bloccare le minacce avanzate.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-uno-sguardo-al-futuro\"><strong>Uno sguardo al futuro<\/strong><\/h3>\n\n\n\n<p>La pandemia di COVID-19 ha evidenziato la necessit\u00e0 di una struttura di cybersecurity efficace, una costante vigilanza e la capacit\u00e0 di adattarsi al mutevole panorama delle minacce. La sicurezza dovrebbe essere una priorit\u00e0 assoluta, e ora \u00e8 il momento di investire in soluzioni pi\u00f9 ampie, pi\u00f9 avanzate e pi\u00f9 adattabili &#8211; soprattutto perch\u00e9 i cybercriminali adottano nuove strategie di attacco per sfruttare i device personali e accedere alle reti aziendali. In quest&#8217;ottica, rafforzare i sistemi delle reti remote deve diventare di primaria importanza.<\/p>\n\n\n\n<p>Il modo migliore per proteggersi da attivit\u00e0 malevole in continua evoluzione \u00e8 adottare un approccio globale e integrato alla cybersecurity. \u00c8 fondamentale garantire l&#8217;accesso costante a informazioni aggiornate sulle minacce e alla formazione. Fortinet si impegna a rispondere a questa esigenza fornendo una visione all&#8217;avanguardia sul panorama delle minacce alla cybersecurity attraverso il team di ricerca dei FortiGuard Labs, tecnologie avanzate di rilevamento delle minacce e una reportistica approfondita sull&#8217;evoluzione dei trend delle minacce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione<\/p>\n","protected":false},"author":1,"featured_media":4830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[4079],"class_list":{"0":"post-4829","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-speciale-sicurezza","8":"tag-fortinet"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020 - BitMAT | Speciale Sicurezza 360x365<\/title>\n<meta name=\"description\" content=\"Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020\" \/>\n<meta property=\"og:description\" content=\"Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\" \/>\n<meta property=\"og:site_name\" content=\"BitMAT | Speciale Sicurezza 360x365\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/BitMATnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-01T13:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-01T13:54:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bitmat.it\/specialesicurezza\/files\/2020\/11\/fortinet_sicurezza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione BitMAT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/BitMATnews\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione BitMAT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\"},\"author\":{\"name\":\"Redazione BitMAT\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/#\\\/schema\\\/person\\\/4cd1e4627f78f4fbed810748dc1a20d4\"},\"headline\":\"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020\",\"datePublished\":\"2020-11-01T13:54:28+00:00\",\"dateModified\":\"2020-11-01T13:54:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\"},\"wordCount\":1498,\"image\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/files\\\/2020\\\/11\\\/fortinet_sicurezza.jpg\",\"keywords\":[\"Fortinet\"],\"articleSection\":[\"Speciale Sicurezza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\",\"url\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\",\"name\":\"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020 - BitMAT | Speciale Sicurezza 360x365\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/files\\\/2020\\\/11\\\/fortinet_sicurezza.jpg\",\"datePublished\":\"2020-11-01T13:54:28+00:00\",\"dateModified\":\"2020-11-01T13:54:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/#\\\/schema\\\/person\\\/4cd1e4627f78f4fbed810748dc1a20d4\"},\"description\":\"Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage\",\"url\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/files\\\/2020\\\/11\\\/fortinet_sicurezza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/files\\\/2020\\\/11\\\/fortinet_sicurezza.jpg\",\"width\":400,\"height\":267,\"caption\":\"Il semestre nero della cybersecurity\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/4829\\\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/#website\",\"url\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/\",\"name\":\"BitMAT | Speciale Sicurezza 360x365\",\"description\":\"Un intero speciale dedicato esclusivamente alla sicurezza, in tutte le sue accezioni: dalla protezione dei singoli device a quella delle infrastrutture critiche, senza trascurare gli attacchi terroristici e la violazione alla privacy.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/#\\\/schema\\\/person\\\/4cd1e4627f78f4fbed810748dc1a20d4\",\"name\":\"Redazione BitMAT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g\",\"caption\":\"Redazione BitMAT\"},\"description\":\"BitMAT Edizioni \u00e8 una casa editrice che ha sede a Milano con una copertura a 360\u00b0 per quanto riguarda la comunicazione rivolta agli specialisti dell'lnformation &amp; Communication Technology.\",\"sameAs\":[\"https:\\\/\\\/www.bitmat.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/BitMATnews\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/BitMATnews\"],\"url\":\"https:\\\/\\\/www.bitmat.it\\\/specialesicurezza\\\/news\\\/author\\\/bitmat\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020 - BitMAT | Speciale Sicurezza 360x365","description":"Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020","og_locale":"it_IT","og_type":"article","og_title":"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020","og_description":"Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione","og_url":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020","og_site_name":"BitMAT | Speciale Sicurezza 360x365","article_author":"https:\/\/www.facebook.com\/BitMATnews","article_published_time":"2020-11-01T13:54:28+00:00","article_modified_time":"2020-11-01T13:54:33+00:00","og_image":[{"width":400,"height":267,"url":"https:\/\/www.bitmat.it\/specialesicurezza\/files\/2020\/11\/fortinet_sicurezza.jpg","type":"image\/jpeg"}],"author":"Redazione BitMAT","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/BitMATnews","twitter_misc":{"Scritto da":"Redazione BitMAT","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#article","isPartOf":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020"},"author":{"name":"Redazione BitMAT","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/#\/schema\/person\/4cd1e4627f78f4fbed810748dc1a20d4"},"headline":"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020","datePublished":"2020-11-01T13:54:28+00:00","dateModified":"2020-11-01T13:54:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020"},"wordCount":1498,"image":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.bitmat.it\/specialesicurezza\/files\/2020\/11\/fortinet_sicurezza.jpg","keywords":["Fortinet"],"articleSection":["Speciale Sicurezza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.bitmat.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020","url":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020","name":"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020 - BitMAT | Speciale Sicurezza 360x365","isPartOf":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage"},"image":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.bitmat.it\/specialesicurezza\/files\/2020\/11\/fortinet_sicurezza.jpg","datePublished":"2020-11-01T13:54:28+00:00","dateModified":"2020-11-01T13:54:33+00:00","author":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/#\/schema\/person\/4cd1e4627f78f4fbed810748dc1a20d4"},"description":"Sulla scia degli enormi cambiamenti in tutti i settori legati alla pandemia di COVID-19, nel 2020 il panorama delle minacce informatiche \u00e8 mutato profondamente rispetto al passato. Fortinet fa il punto della situazione","breadcrumb":{"@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#primaryimage","url":"https:\/\/www.bitmat.it\/specialesicurezza\/files\/2020\/11\/fortinet_sicurezza.jpg","contentUrl":"https:\/\/www.bitmat.it\/specialesicurezza\/files\/2020\/11\/fortinet_sicurezza.jpg","width":400,"height":267,"caption":"Il semestre nero della cybersecurity"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/4829\/fortinet-come-e-cambiato-il-panorama-delle-minacce-nel-2020#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bitmat.it\/specialesicurezza\/"},{"@type":"ListItem","position":2,"name":"Fortinet: come \u00e8 cambiato il panorama delle minacce nel 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/#website","url":"https:\/\/www.bitmat.it\/specialesicurezza\/","name":"BitMAT | Speciale Sicurezza 360x365","description":"Un intero speciale dedicato esclusivamente alla sicurezza, in tutte le sue accezioni: dalla protezione dei singoli device a quella delle infrastrutture critiche, senza trascurare gli attacchi terroristici e la violazione alla privacy.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bitmat.it\/specialesicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.bitmat.it\/specialesicurezza\/#\/schema\/person\/4cd1e4627f78f4fbed810748dc1a20d4","name":"Redazione BitMAT","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc68cb64f5606ebc4c95ec5b02440c57fc7d268268e5dd8c1cac7ec09ec07ac9?s=96&d=mm&r=g","caption":"Redazione BitMAT"},"description":"BitMAT Edizioni \u00e8 una casa editrice che ha sede a Milano con una copertura a 360\u00b0 per quanto riguarda la comunicazione rivolta agli specialisti dell'lnformation &amp; Communication Technology.","sameAs":["https:\/\/www.bitmat.it\/","https:\/\/www.facebook.com\/BitMATnews","https:\/\/x.com\/https:\/\/twitter.com\/BitMATnews"],"url":"https:\/\/www.bitmat.it\/specialesicurezza\/news\/author\/bitmat"}]}},"_links":{"self":[{"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/posts\/4829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/comments?post=4829"}],"version-history":[{"count":1,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/posts\/4829\/revisions"}],"predecessor-version":[{"id":4831,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/posts\/4829\/revisions\/4831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/media\/4830"}],"wp:attachment":[{"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/media?parent=4829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/categories?post=4829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bitmat.it\/specialesicurezza\/wp-json\/wp\/v2\/tags?post=4829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}